{"id":8033,"date":"2022-11-04T06:50:42","date_gmt":"2022-11-04T09:50:42","guid":{"rendered":"https:\/\/www.rosarioalerta.com.ar\/site\/?p=8033"},"modified":"2022-11-04T06:54:56","modified_gmt":"2022-11-04T09:54:56","slug":"al-menos-tres-heridos-y-varias-balaceras-en-rosario","status":"publish","type":"post","link":"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/8033","title":{"rendered":"<strong>Al menos tres heridos y varias balaceras en Rosario<\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las v\u00edctimas, se retir\u00f3 del efector p\u00fablico sin recibir el alta m\u00e9dica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pasadas las 20, ingresa al <strong>Hospital Alberdi<\/strong>, un hombre de 30 a\u00f1os, con heridas de bala en abdomen y extremidades superiores, dado el estado de gravedad provocado por las heridas, fue trasladado al <strong>Hospital de Emergencias Clemente \u00c1lvarez (HECA) <\/strong>quedando internado con pron\u00f3stico reservado. Mientras tanto al <strong>Hospital Centenario<\/strong> ingresa un joven de 23 a\u00f1os con heridas de bala en dorso y axila, con pron\u00f3stico de salud cr\u00edtico, qued\u00f3 en la sala de cuidados intensivos. Seg\u00fan los primeros trascendidos, la balacera habr\u00eda tenido como escenario la esquina de <strong>G\u00e9nova y Asturias<\/strong>, tambi\u00e9n en <strong>G\u00e9nova y Ottone<\/strong> logr\u00f3 el <strong>Gabinete<\/strong> <strong>Criminal\u00edstico de la AIC<\/strong> recoger rastros de sangre y vainas servidas. Y cerca de la medianoche, hubo otra balacera de la que se desconocen si se registraron lesionados en inmediaciones de <strong>V\u00edctor Cue y Reconquista<\/strong>, fuentes vecinales reportaron de este \u00faltimo ataque m\u00e1s de diez detonaciones<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2026<strong>m\u00e1s heridos<\/strong>\u2026 Al <strong>HECA<\/strong> tambi\u00e9n ingresa cerca de la medianoche un hombre de 31 a\u00f1os con heridas punzo cortantes m\u00faltiples en extremidades superiores y rostro, retir\u00e1ndose de la sala de guardia, sin recibir el alta m\u00e9dica. Tambi\u00e9n se desconoce donde habr\u00eda sido agredido, aunque se presume que podr\u00eda haber participado de una ri\u00f1a callejera<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2026<strong>finalmente<\/strong>\u2026 en la zona de <strong>Villa La Lata<\/strong>, vecinos, denunciaron haber escuchado una r\u00e1faga de disparos, cerca de la medianoche. No se habr\u00edan reportado heridos y se aguarda el informa de la <strong>AIC<\/strong> sobre la recolecci\u00f3n de vainas servidas<\/p>\n<div class=\"newspaper-x-tags\"><strong>TAGS: <\/strong><span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/inseguridad\" rel=\"tag\">inseguridad<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/noticias-de-rosario\" rel=\"tag\">Noticias de Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/perotti\" rel=\"tag\">Perotti<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/rosario\" rel=\"tag\">Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/santa-fe\" rel=\"tag\">Santa Fe<\/a> <\/div>","protected":false},"excerpt":{"rendered":"<p>Una de las v\u00edctimas, se retir\u00f3 del efector p\u00fablico sin recibir el alta m\u00e9dica Pasadas las 20, ingresa al Hospital Alberdi, un hombre de 30 a\u00f1os, con heridas de bala en abdomen y extremidades superiores, dado el estado de gravedad provocado por las heridas, fue trasladado al Hospital de Emergencias Clemente \u00c1lvarez (HECA) quedando internado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[15,17,66,21,14],"tags":[54,95,24,55,65],"class_list":["post-8033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-balaceras","category-heridos","category-inseguridad","category-noticias","category-policiales","tag-inseguridad","tag-noticias-de-rosario","tag-perotti","tag-rosario","tag-santa-fe"],"_links":{"self":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/8033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/comments?post=8033"}],"version-history":[{"count":2,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/8033\/revisions"}],"predecessor-version":[{"id":8036,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/8033\/revisions\/8036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media\/8035"}],"wp:attachment":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media?parent=8033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/categories?post=8033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/tags?post=8033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}