{"id":4311,"date":"2022-03-05T21:18:08","date_gmt":"2022-03-06T00:18:08","guid":{"rendered":"https:\/\/www.rosarioalerta.com.ar\/site\/?p=4311"},"modified":"2022-03-05T21:18:09","modified_gmt":"2022-03-06T00:18:09","slug":"vas-a-tener-que-darme-50-mil-o-te-mato-a-tu-mama","status":"publish","type":"post","link":"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/4311","title":{"rendered":"\u201cVas a tener que darme 50 mil o te mato a tu mam\u00e1\u201d"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Dos amenazas m\u00e1s tuvieron lugar en la zona suroeste de Rosario<\/p>\n\n\n\n<p>Esta tarde en <strong>Avellaneda al 7100<\/strong>, un sujeto apodado \u201c<strong><em>Chapita<\/em><\/strong>\u201d amenaz\u00f3 de muerte a un joven de 24 a\u00f1os, cuando este hac\u00eda mandados. Al cruzarlo en la v\u00eda p\u00fablica le dijo <strong><em>\u201cVos y tu mam\u00e1 me batieron la cana, van a tener que darme 50 mil o te la mato a tu mam\u00e1\u201d.<\/em><\/strong> Momentos m\u00e1s tarde escucharon disparos en las cercan\u00edas a su vivienda, llegando sujetos en moto, quienes comenzaron a patear la puerta, sin lograr ingresar.<\/p>\n\n\n\n<p>Por ello decidieron radicar la denuncia en la <strong>Comisar\u00eda 32\u00ba<\/strong><\/p>\n\n\n\n<p>..<strong>el otro caso<\/strong>\u2026 horas m\u00e1s tarde en <strong>Bv Segu\u00ed al 8100<\/strong>, un hombre de 46 a\u00f1os, se levant\u00f3 de dormir la siesta y al salir a su patio se encontr\u00f3 con una nota que rezaba; <strong><em>\u201ccomunicate o plomo llama o manda Whatsapp al\u2026. Ten\u00e9s dos horas\u201d<\/em><\/strong><\/p>\n\n\n\n<p>Las actuaciones recayeron en la misma seccional que el anterior caso<\/p>\n<div class=\"newspaper-x-tags\"><strong>TAGS: <\/strong><span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/amenazas\" rel=\"tag\">Amenazas<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/inseguridad\" rel=\"tag\">inseguridad<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/noticias-de-rosario\" rel=\"tag\">Noticias de Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/perotti\" rel=\"tag\">Perotti<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/rosario\" rel=\"tag\">Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/santa-fe\" rel=\"tag\">Santa Fe<\/a> <\/div>","protected":false},"excerpt":{"rendered":"<p>Dos amenazas m\u00e1s tuvieron lugar en la zona suroeste de Rosario Esta tarde en Avellaneda al 7100, un sujeto apodado \u201cChapita\u201d amenaz\u00f3 de muerte a un joven de 24 a\u00f1os, cuando este hac\u00eda mandados. Al cruzarlo en la v\u00eda p\u00fablica le dijo \u201cVos y tu mam\u00e1 me batieron la cana, van a tener que darme [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4312,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[66,21,14],"tags":[104,54,95,24,55,65],"class_list":["post-4311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inseguridad","category-noticias","category-policiales","tag-amenazas","tag-inseguridad","tag-noticias-de-rosario","tag-perotti","tag-rosario","tag-santa-fe"],"_links":{"self":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/4311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/comments?post=4311"}],"version-history":[{"count":1,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/4311\/revisions"}],"predecessor-version":[{"id":4313,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/4311\/revisions\/4313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media\/4312"}],"wp:attachment":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media?parent=4311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/categories?post=4311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/tags?post=4311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}