{"id":28607,"date":"2025-10-27T09:32:45","date_gmt":"2025-10-27T12:32:45","guid":{"rendered":"https:\/\/www.rosarioalerta.com.ar\/site\/?p=28607"},"modified":"2025-10-27T09:32:45","modified_gmt":"2025-10-27T12:32:45","slug":"tres-menores-heridos-y-aprehendidos-tras-un-enfrentamiento","status":"publish","type":"post","link":"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/28607","title":{"rendered":"Tres menores heridos y aprehendidos tras un enfrentamiento"},"content":{"rendered":"\n<p>Ocurri\u00f3 durante la madrugada en la zona sur de la ciudad<\/p>\n\n\n\n<p>El episodio se registr\u00f3 en la madrugada del lunes, minutos antes de las 2, cuando personal policial, realizaba tareas de patrullaje por <strong>Ayacucho al 3900, <\/strong>a la altura de <strong>Ameghino y Pasaje Esperanto<\/strong>, en la zona sur de Rosario.<br>De acuerdo con la informaci\u00f3n oficial, los agentes escucharon al menos diez detonaciones y al llegar al lugar observaron dos grupos de hombres enfrent\u00e1ndose con armas de fuego. Al descender del m\u00f3vil, varios individuos corrieron hacia el personal policial y efectuaron disparos, lo que motiv\u00f3 que un suboficial repeliera la agresi\u00f3n con su arma reglamentaria. No se registraron uniformados lesionados.<\/p>\n\n\n\n<p>Minutos despu\u00e9s, desde la Central de Emergencias del 911, informaron sobre el ingreso de tres j\u00f3venes heridos de bala a distintos centros de salud.<br>El primero, <strong>Benjam\u00edn Mat\u00edas M. (17),<\/strong> fue derivado desde el <strong>Hospital Roque S\u00e1enz Pe\u00f1a <\/strong>al<strong> HECA<\/strong>, con una herida de arma de fuego en el abdomen.<br>El segundo, <strong>Jerem\u00edas Andr\u00e9s T. (16<\/strong>), ingres\u00f3 por sus propios medios al <strong>HECA<\/strong> acompa\u00f1ado de su pareja, con una herida en el pie derecho.<br>El tercero, <strong>Waldo L. (16),<\/strong> presentaba una lesi\u00f3n en el muslo derecho.<br>Los tres fueron aprehendidos en calidad de investigados por su presunta participaci\u00f3n en el enfrentamiento.<\/p>\n\n\n\n<p>Durante el procedimiento, el personal interviniente localiz\u00f3 la presencia de una Bersa calibre 9 mil\u00edmetros sobre el techo de una vivienda en <strong>Ayacucho y Ameghino.<br><\/strong>La <strong>Polic\u00eda de Investigaciones<\/strong> (PDI) realiz\u00f3 las pericias correspondientes y secuestr\u00f3 el arma, mientras que la <strong>Comisar\u00eda 15\u00ba<\/strong> tom\u00f3 intervenci\u00f3n en la causa.<br>La Fiscal\u00eda en turno dispuso la recolecci\u00f3n de im\u00e1genes de c\u00e1maras de seguridad, toma de testimonios y dem\u00e1s medidas tendientes a establecer las circunstancias y responsabilidades del hecho.<\/p>\n<div class=\"newspaper-x-tags\"><strong>TAGS: <\/strong><span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/noticias-de-rosario\" rel=\"tag\">Noticias de Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/rosario\" rel=\"tag\">Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/santa-fe\" rel=\"tag\">Santa Fe<\/a> <\/div>","protected":false},"excerpt":{"rendered":"<p>Ocurri\u00f3 durante la madrugada en la zona sur de la ciudad El episodio se registr\u00f3 en la madrugada del lunes, minutos antes de las 2, cuando personal policial, realizaba tareas de patrullaje por Ayacucho al 3900, a la altura de Ameghino y Pasaje Esperanto, en la zona sur de Rosario.De acuerdo con la informaci\u00f3n oficial, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":28608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[11,17,21,14],"tags":[95,55,65],"class_list":["post-28607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-detenidos","category-heridos","category-noticias","category-policiales","tag-noticias-de-rosario","tag-rosario","tag-santa-fe"],"_links":{"self":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/28607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/comments?post=28607"}],"version-history":[{"count":1,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/28607\/revisions"}],"predecessor-version":[{"id":28609,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/28607\/revisions\/28609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media\/28608"}],"wp:attachment":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media?parent=28607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/categories?post=28607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/tags?post=28607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}