{"id":26814,"date":"2025-08-01T08:41:46","date_gmt":"2025-08-01T11:41:46","guid":{"rendered":"https:\/\/www.rosarioalerta.com.ar\/site\/?p=26814"},"modified":"2025-08-01T08:41:48","modified_gmt":"2025-08-01T11:41:48","slug":"abuso-amenazas-y-droga","status":"publish","type":"post","link":"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/26814","title":{"rendered":"Abuso, amenazas y droga"},"content":{"rendered":"\n<p>Dos casos que revelan la violencia oculta en lo cotidiano<\/p>\n\n\n\n<p>En menos de 24 horas, dos intervenciones policiales en <strong>Rosario y Funes<\/strong> expusieron situaciones graves: abuso sexual contra menores y tenencia ilegal de marihuana en un domicilio allanado por una denuncia de violencia de g\u00e9nero.<\/p>\n\n\n\n<p>La violencia en sus m\u00faltiples formas volvi\u00f3 a manifestarse con crudeza en la regi\u00f3n. En dos hechos ocurridos con pocas horas de diferencia, personal policial de <strong>Rosario y Funes<\/strong> actu\u00f3 en situaciones que involucraron desde abuso sexual hasta la tenencia ilegal de plantas de cannabis en el marco de un conflicto por violencia de g\u00e9nero. El primero de los episodios tuvo lugar en <strong>Sarmiento al 800<\/strong>, en la ciudad de <strong>Funes<\/strong>, donde una mujer denunci\u00f3 que su ex pareja le imped\u00eda ingresar al domicilio que compart\u00edan, adem\u00e1s de amenazarla verbalmente. Mientras radicaba la denuncia, un vecino alert\u00f3 que dos hombres hab\u00edan entrado a la vivienda. Al llegar, el personal policial encontr\u00f3 a los sujetos \u2014supuestamente enviados por el ex\u2014 dentro de la propiedad. All\u00ed se descubri\u00f3 <strong>una carpa \u201cindoor\u201d con seis plantas de marihuana, extractores, reflectores, una bolsa con cuatro plantas m\u00e1s y frascos con flores de cannabis.<\/strong> Los dos hombres fueron detenidos junto con un menor. El material fue secuestrado bajo la figura de infracci\u00f3n a la Ley 23.737.<\/p>\n\n\n\n<p>Mientras tanto, en Rosario, durante la madrugada, una llamada a la <strong>Central de Emergencias del 911<\/strong> moviliz\u00f3 a la polic\u00eda, hacia <strong>Felipe Mor\u00e9 al 2500<\/strong> por un presunto abuso sexual. Una joven de 26 a\u00f1os y dos ni\u00f1as, de 10 y 12 a\u00f1os, fueron las v\u00edctimas. Un familiar de la denunciante logr\u00f3 seguir al presunto agresor, identificado como <strong>Julio C\u00e9sar M de 38 a\u00f1os<\/strong> y lo se\u00f1al\u00f3 ante la polic\u00eda. Fue arrestado en <strong>Riobamba al 6400<\/strong>. El fiscal de delitos sexuales, Diego Mineiro, dispuso la asistencia de las v\u00edctimas en el <strong>Centro de Atenci\u00f3n a la V\u00edctima de Delitos Sexuales<\/strong> (CAVS) y el traslado del imputado a la <strong>Comisar\u00eda 32\u00ba<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.rosarioalerta.com.ar\/site\/wp-content\/uploads\/2025\/08\/Violin-3-1024x576.jpg\" alt=\"\" class=\"wp-image-26816\" srcset=\"https:\/\/www.rosarioalerta.com.ar\/site\/wp-content\/uploads\/2025\/08\/Violin-3-1024x576.jpg 1024w, https:\/\/www.rosarioalerta.com.ar\/site\/wp-content\/uploads\/2025\/08\/Violin-3-300x169.jpg 300w, https:\/\/www.rosarioalerta.com.ar\/site\/wp-content\/uploads\/2025\/08\/Violin-3-768x432.jpg 768w, https:\/\/www.rosarioalerta.com.ar\/site\/wp-content\/uploads\/2025\/08\/Violin-3-1536x864.jpg 1536w, https:\/\/www.rosarioalerta.com.ar\/site\/wp-content\/uploads\/2025\/08\/Violin-3.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Ambos casos, aunque diferentes, evidencian una constante: la vulnerabilidad de las v\u00edctimas en escenarios donde lo cotidiano se vuelve peligroso. Detr\u00e1s de una separaci\u00f3n o en el silencio de la noche, el riesgo puede aparecer sin previo aviso. Desde la amenaza de un ex hasta un abuso sexual contra menores, estas historias nos obligan a mirar m\u00e1s all\u00e1 de las estad\u00edsticas. Porque detr\u00e1s de cada intervenci\u00f3n policial hay vidas, v\u00ednculos rotos, derechos vulnerados y una sociedad que a\u00fan lucha por proteger lo b\u00e1sico: la integridad de sus ciudadanos. Actuar r\u00e1pido es clave, pero prevenir sigue siendo el mayor desaf\u00edo.<\/p>\n<div class=\"newspaper-x-tags\"><strong>TAGS: <\/strong><span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/funes\" rel=\"tag\">funes<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/noticias-de-funes\" rel=\"tag\">Noticias de Funes<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/noticias-de-rosario\" rel=\"tag\">Noticias de Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/rosario\" rel=\"tag\">Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/santa-fe\" rel=\"tag\">Santa Fe<\/a> <\/div>","protected":false},"excerpt":{"rendered":"<p>Dos casos que revelan la violencia oculta en lo cotidiano En menos de 24 horas, dos intervenciones policiales en Rosario y Funes expusieron situaciones graves: abuso sexual contra menores y tenencia ilegal de marihuana en un domicilio allanado por una denuncia de violencia de g\u00e9nero. La violencia en sus m\u00faltiples formas volvi\u00f3 a manifestarse con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[11,494,21,14,51],"tags":[46,137,95,55,65],"class_list":["post-26814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-detenidos","category-microtrafico","category-noticias","category-policiales","category-violencia-de-genero","tag-funes","tag-noticias-de-funes","tag-noticias-de-rosario","tag-rosario","tag-santa-fe"],"_links":{"self":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/26814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/comments?post=26814"}],"version-history":[{"count":1,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/26814\/revisions"}],"predecessor-version":[{"id":26817,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/26814\/revisions\/26817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media\/26815"}],"wp:attachment":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media?parent=26814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/categories?post=26814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/tags?post=26814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}