{"id":26657,"date":"2025-07-25T07:10:15","date_gmt":"2025-07-25T10:10:15","guid":{"rendered":"https:\/\/www.rosarioalerta.com.ar\/site\/?p=26657"},"modified":"2025-07-25T07:10:24","modified_gmt":"2025-07-25T10:10:24","slug":"ciclistas-en-la-mira","status":"publish","type":"post","link":"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/26657","title":{"rendered":"Ciclistas en la mira?"},"content":{"rendered":"\n<p>Varios robos a ciclistas y heridos en algunos casos<\/p>\n\n\n\n<p>Un joven de 20 a\u00f1os fue herido de un disparo en la espalda al resistirse al robo de su bicicleta. No fue el \u00fanico caso: una serie de ataques similares en distintos puntos de Rosario despierta preocupaci\u00f3n.<\/p>\n\n\n\n<p>La noche del jueves, Rosario sum\u00f3 un nuevo episodio violento que pone el foco en una modalidad delictiva que crece: el robo a ciclistas. Pasadas las 20, un joven de 20 a\u00f1os fue atacado en la intersecci\u00f3n de <strong>Ovidio Lagos y Amen\u00e1bar, <\/strong>en plena v\u00eda p\u00fablica. Seg\u00fan fuentes policiales, el muchacho fue interceptado por delincuentes que lo amenazaron con un arma de fuego. Al resistirse al robo de su bicicleta y su celular, recibi\u00f3 un disparo que le provoc\u00f3 una herida en el om\u00f3plato. Fue trasladado al <strong>Hospital Carrasco<\/strong>, donde permanece internado con fractura de om\u00f3plato<\/p>\n\n\n\n<p>Lo m\u00e1s alarmante es que no se trat\u00f3 de un caso aislado. Solo en las \u00faltimas 24 horas, se reportaron al menos cinco robos similares en diferentes barrios de la ciudad. En uno de ellos, un hombre de 41 a\u00f1os fue golpeado por motochorros en <strong>San Nicol\u00e1s al 2500<\/strong> y despojado de su bicicleta. En otro, tres delincuentes atacaron a un trabajador que sal\u00eda del shopping Alto Rosario. Todos los hechos tienen algo en com\u00fan: la violencia extrema y la impunidad con la que act\u00faan los ladrones.<\/p>\n\n\n\n<p>La presencia de casquillos de 9 mm encontrados en el lugar del ataque en <strong>Ov. Lagos al 3900<\/strong>, refuerza la hip\u00f3tesis de que los delincuentes no solo act\u00faan armados, sino dispuestos a disparar. Incluso al aire, como forma de intimidaci\u00f3n o aviso de dominio territorial.<\/p>\n\n\n\n<p>La ola de robos a ciclistas con armas de fuego plantea un nuevo desaf\u00edo a la seguridad p\u00fablica. En <strong>V\u00e9lez Sarsfield y Formosa<\/strong> gatillaron al aire, para que un hombre entregue su bicicleta, mientras que una mujer de 62 a\u00f1os fue asaltada por dos delincuentes en <strong>Segu\u00ed y Dorrego<\/strong>, le mostraron un arma de fuego y le sustrajeron un celular y la billetera<\/p>\n<div class=\"newspaper-x-tags\"><strong>TAGS: <\/strong><span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/noticias-de-rosario\" rel=\"tag\">Noticias de Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/rosario\" rel=\"tag\">Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/santa-fe\" rel=\"tag\">Santa Fe<\/a> <\/div>","protected":false},"excerpt":{"rendered":"<p>Varios robos a ciclistas y heridos en algunos casos Un joven de 20 a\u00f1os fue herido de un disparo en la espalda al resistirse al robo de su bicicleta. No fue el \u00fanico caso: una serie de ataques similares en distintos puntos de Rosario despierta preocupaci\u00f3n. La noche del jueves, Rosario sum\u00f3 un nuevo episodio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26658,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[15,17,21,14,2],"tags":[95,55,65],"class_list":["post-26657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-balaceras","category-heridos","category-noticias","category-policiales","category-robos","tag-noticias-de-rosario","tag-rosario","tag-santa-fe"],"_links":{"self":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/26657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/comments?post=26657"}],"version-history":[{"count":1,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/26657\/revisions"}],"predecessor-version":[{"id":26659,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/26657\/revisions\/26659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media\/26658"}],"wp:attachment":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media?parent=26657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/categories?post=26657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/tags?post=26657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}