{"id":21125,"date":"2024-11-05T22:01:56","date_gmt":"2024-11-06T01:01:56","guid":{"rendered":"https:\/\/www.rosarioalerta.com.ar\/site\/?p=21125"},"modified":"2024-11-05T22:09:03","modified_gmt":"2024-11-06T01:09:03","slug":"rescatan-un-aguara-guazu-en-el-aeropuerto","status":"publish","type":"post","link":"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/21125","title":{"rendered":"Rescatan un Aguar\u00e1 Guaz\u00fa en el Aeropuerto"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Personal de la Brigada Ecol\u00f3gica y e Rescate Animal logr\u00f3 poner a salvo un animal en extinci\u00f3n<\/p>\n\n\n\n<p>En una jornada destacada para la protecci\u00f3n de la fauna, la <strong>Brigada Ecol\u00f3gica y de Rescate Animal<\/strong> de la Unidad Regional II realiz\u00f3 un importante operativo de rescate de un <strong>aguar\u00e1 guaz\u00fa<\/strong>, un ejemplar en grave peligro de extinci\u00f3n, que deambulaba por el sector de pista del Aeropuerto de Rosario.<\/p>\n\n\n\n<p>Fue en las primeras horas de la ma\u00f1ana de este martes, cuando, la oficial <strong>Romina Aguirre, y los suboficiales Emiliano Mohe, Juan Galarza y Franco Godoy<\/strong>, se constituyeron en el lugar luego de recibir el alerta sobre la presencia del animal. Con un trabajo coordinado, utilizaron los m\u00f3viles operativos para realizar maniobras de acorralamiento, logrando capturar al ejemplar hembra joven sin que sufriera da\u00f1os. Tras un examen veterinario, el diagn\u00f3stico fue positivo: el animal se encontraba en buen estado de salud, apto para su liberaci\u00f3n.<\/p>\n\n\n\n<p>La brigada coordin\u00f3 con la <strong>Direcci\u00f3n de Fauna<\/strong> y la directora del protocolo de <strong>aguar\u00e1 guaz\u00fa<\/strong>, para proceder con la liberaci\u00f3n en una zona de monte cercana a <strong>Serodino<\/strong>. La acci\u00f3n culmin\u00f3 con \u00e9xito horas m\u00e1s tarde, cuando el animal fue liberado en su h\u00e1bitat natural.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"newspaper-x-video-container\"><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/Rosario?src=hash&amp;ref_src=twsrc%5Etfw\">#Rosario<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/BrigadaEcol%C3%B3gica?src=hash&amp;ref_src=twsrc%5Etfw\">#BrigadaEcol\u00f3gica<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/VGG?src=hash&amp;ref_src=twsrc%5Etfw\">#VGG<\/a>  <a href=\"https:\/\/t.co\/9TQ2as09vZ\">https:\/\/t.co\/9TQ2as09vZ<\/a> a trav\u00e9s de <a href=\"https:\/\/twitter.com\/RosarioAlerta?ref_src=twsrc%5Etfw\">@RosarioAlerta<\/a> <a href=\"https:\/\/t.co\/LLCjBks7hr\">pic.twitter.com\/LLCjBks7hr<\/a><\/p>&mdash; Rosario Alerta (@RosarioAlerta) <a href=\"https:\/\/twitter.com\/RosarioAlerta\/status\/1853967166321861089?ref_src=twsrc%5Etfw\">November 6, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<\/div><\/figure>\n\n\n\n<p>En paralelo, antes del mediod\u00eda, otra unidad de la misma Brigada recibi\u00f3 un llamado desde <strong>Villa Gobernador G\u00e1lvez<\/strong> informando sobre la presencia de un mono en un \u00e1rbol, con vecinos intentando cazarlo. Al llegar al lugar, confirmaron el hecho y tras investigar, determinaron que el animal hab\u00eda escapado de un domicilio. Durante el operativo, tambi\u00e9n se encontraron varias aves aut\u00f3ctonas en el lugar y se procedi\u00f3 a la aprehensi\u00f3n de una mujer, adem\u00e1s del secuestro de una escopeta, por la presunta caza ilegal.<\/p>\n\n\n\n<p>Estos dos operativos demuestran el compromiso de la Brigada Ecol\u00f3gica y de Rescate Animal en la protecci\u00f3n de la fauna local y la pronta respuesta ante cualquier amenaza hacia las especies en peligro. La actuaci\u00f3n oportuna y la colaboraci\u00f3n interinstitucional son clave para la conservaci\u00f3n de la biodiversidad en la regi\u00f3n.<\/p>\n<div class=\"newspaper-x-tags\"><strong>TAGS: <\/strong><span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/noticias-de-rosario\" rel=\"tag\">Noticias de Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/noticias-de-vgg\" rel=\"tag\">Noticias de VGG<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/rosario\" rel=\"tag\">Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/santa-fe\" rel=\"tag\">Santa Fe<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/vgg\" rel=\"tag\">VGG<\/a> <\/div>","protected":false},"excerpt":{"rendered":"<p>Personal de la Brigada Ecol\u00f3gica y e Rescate Animal logr\u00f3 poner a salvo un animal en extinci\u00f3n En una jornada destacada para la protecci\u00f3n de la fauna, la Brigada Ecol\u00f3gica y de Rescate Animal de la Unidad Regional II realiz\u00f3 un importante operativo de rescate de un aguar\u00e1 guaz\u00fa, un ejemplar en grave peligro de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21126,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[21,14,8],"tags":[95,94,55,65,60],"class_list":["post-21125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-policiales","category-proteccion-de-animales","tag-noticias-de-rosario","tag-noticias-de-vgg","tag-rosario","tag-santa-fe","tag-vgg"],"_links":{"self":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/21125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/comments?post=21125"}],"version-history":[{"count":2,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/21125\/revisions"}],"predecessor-version":[{"id":21128,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/21125\/revisions\/21128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media\/21126"}],"wp:attachment":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media?parent=21125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/categories?post=21125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/tags?post=21125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}