{"id":21105,"date":"2024-11-05T07:14:40","date_gmt":"2024-11-05T10:14:40","guid":{"rendered":"https:\/\/www.rosarioalerta.com.ar\/site\/?p=21105"},"modified":"2024-11-05T07:14:41","modified_gmt":"2024-11-05T10:14:41","slug":"detienen-a-un-hombre-por-intento-de-homicidio","status":"publish","type":"post","link":"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/21105","title":{"rendered":"Detienen a un hombre por intento de homicidio"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>La Polic\u00eda de Investigaciones llev\u00f3 adelante un allanamiento en <strong>Villa Gobernador G\u00e1lvez<\/strong><\/p>\n\n\n\n<p>&nbsp;Seg\u00fan las primeras pruebas recabadas, un joven de 26 a\u00f1os fue se\u00f1alado de intentar asesinar a un hombre de 54 a\u00f1os en un ataque ocurrido durante el mes de septiembre.<\/p>\n\n\n\n<p>La <strong>Polic\u00eda de Investigaciones<\/strong> (PDI), detuvo a un hombre de 26 a\u00f1os, por el delito de homicidio simple en grado de tentativa. La detenci\u00f3n se produjo en el marco de una investigaci\u00f3n iniciada tras un ataque ocurrido en septiembre en la localidad de <strong>Villa Gobernador G\u00e1lvez<\/strong>, donde una persona de 54 a\u00f1os result\u00f3 gravemente herida con un arma blanca.<\/p>\n\n\n\n<p>El hecho que desencaden\u00f3 la investigaci\u00f3n ocurri\u00f3 en el mes de septiembre, cuando la v\u00edctima fue agredida violentamente en la v\u00eda p\u00fablica. Tras recibir atenci\u00f3n m\u00e9dica por las heridas provocadas por un cuchillo, los agentes del Departamento Operativo de la PDI comenzaron las tareas de investigaci\u00f3n que, con el tiempo, permitieron identificar al presunto agresor.<\/p>\n\n\n\n<p>Con la intervenci\u00f3n de la Fiscal\u00eda interviniente, se emitieron \u00f3rdenes judiciales de allanamiento que fueron ejecutadas con \u00e9xito en un domicilio de la ciudad de <strong>Villa Gobernador G\u00e1lvez<\/strong>, ubicado en la calle <strong>Jos\u00e9 Ingenieros al 100 bis, <\/strong>mientras tanto el restante se llev\u00f3 adelante en la zona sur de Rosario, en<strong> Plat\u00f3n y Ulises<\/strong>. Durante los operativos, se secuestraron varios celulares, que ser\u00e1n sometidos a peritajes para determinar si contienen evidencia relevante para la causa.<\/p>\n\n\n\n<p>El procedimiento fue llevado a cabo por la <strong>PDI<\/strong> con el apoyo de los grupos de irrupci\u00f3n <strong>GIRI<\/strong> (Grupo de Inspecci\u00f3n y Respuesta Inmediata) y <strong>GTM<\/strong> (Grupo T\u00e1ctico de M\u00f3viles) de la Unidad Regional II, quienes colaboraron en la ejecuci\u00f3n de los allanamientos con el objetivo de garantizar la seguridad durante el operativo.<\/p>\n\n\n\n<p>La investigaci\u00f3n contin\u00faa, y la detenci\u00f3n de este sujeto, representa un avance significativo en la resoluci\u00f3n de este violento caso. Seg\u00fan fuentes cercanas a la causa, la fiscal\u00eda trabajar\u00e1 en la recopilaci\u00f3n de m\u00e1s pruebas que puedan confirmar la responsabilidad del detenido en el intento de homicidio.<\/p>\n<div class=\"newspaper-x-tags\"><strong>TAGS: <\/strong><span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/noticias-de-rosario\" rel=\"tag\">Noticias de Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/noticias-de-vgg\" rel=\"tag\">Noticias de VGG<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/rosario\" rel=\"tag\">Rosario<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/santa-fe\" rel=\"tag\">Santa Fe<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/vgg\" rel=\"tag\">VGG<\/a> <\/div>","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda de Investigaciones llev\u00f3 adelante un allanamiento en Villa Gobernador G\u00e1lvez &nbsp;Seg\u00fan las primeras pruebas recabadas, un joven de 26 a\u00f1os fue se\u00f1alado de intentar asesinar a un hombre de 54 a\u00f1os en un ataque ocurrido durante el mes de septiembre. La Polic\u00eda de Investigaciones (PDI), detuvo a un hombre de 26 a\u00f1os, por [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[12,11,21,14],"tags":[95,94,55,65,60],"class_list":["post-21105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allanamientos","category-detenidos","category-noticias","category-policiales","tag-noticias-de-rosario","tag-noticias-de-vgg","tag-rosario","tag-santa-fe","tag-vgg"],"_links":{"self":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/21105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/comments?post=21105"}],"version-history":[{"count":1,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/21105\/revisions"}],"predecessor-version":[{"id":21107,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/21105\/revisions\/21107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media\/21106"}],"wp:attachment":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media?parent=21105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/categories?post=21105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/tags?post=21105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}