{"id":10404,"date":"2023-05-29T20:05:43","date_gmt":"2023-05-29T23:05:43","guid":{"rendered":"https:\/\/www.rosarioalerta.com.ar\/site\/?p=10404"},"modified":"2023-05-29T20:05:44","modified_gmt":"2023-05-29T23:05:44","slug":"un-camion-se-llevo-puesto-siete-autos-y-una-moto","status":"publish","type":"post","link":"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/10404","title":{"rendered":"Un cami\u00f3n se llev\u00f3 puesto siete autos y una moto"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Como saldo hubo varios heridos y una mujer falleci\u00f3 a pesar de los esfuerzos de los profesionales de la salud<\/p>\n\n\n\n<p>En horas de este mediod\u00eda, un espectacular siniestro vial se registr\u00f3 en <strong>Villa Gobernador G\u00e1lvez<\/strong>, en las inmediaciones de <strong>San Mart\u00edn y General L\u00f3pez,<\/strong> donde se encontraban siete automovilistas y una moto con dos ocupantes, esperando la luz verde del sem\u00e1foro, cuando llega por detr\u00e1s cami\u00f3n de la empresa <strong>Los Olivos<\/strong> con carga de cemento y colisiona contra los siete veh\u00edculos que estaban estacionados, adem\u00e1s tumba una columna de cemento.<\/p>\n\n\n\n<p>Como saldo varias personas con politraumatismos varios y da\u00f1os materiales en sus autom\u00f3viles; un Ford Focus, Un Citro\u00ebn, que ten\u00eda dos personas dentro del rodado, un Fiat Palio, un taxista a bordo de un VW Virtus que trasladaba a una pasajera, un Fiat Mobi, un Peugeot 306 y una Renault Oroch. Tambi\u00e9n atr\u00e1s de todo, se encontraba una motocicleta tipo 110 cc con dos personas a bordo, de las cuales una presentaba heridas de gravedad y su pareja, fue trasladada por el <strong>Helic\u00f3ptero Sanitario<\/strong>, pero a pesar de los esfuerzos de los profesionales de la salud por mantener con vida a la mujer, esta fallece<\/p>\n\n\n\n<p>En tanto, se investiga la mec\u00e1nica del episodio, no descartan una falla en la mec\u00e1nica del cami\u00f3n y la <strong>Dra Prunotto de la Unidad de Homicidios Culposos<\/strong>, orden\u00f3 la aprehensi\u00f3n del chofer; <strong>Mario Luis V de 29 a\u00f1os<\/strong> y la realizaci\u00f3n de los ex\u00e1menes alcoholuria, alcoholemia y narcoholemia.<\/p>\n\n\n\n<p>Del incidente participaron ambulancias del <strong>SIES<\/strong> y el <strong>Helic\u00f3ptero Sanitario<\/strong>, personal municipal y bomberos voluntarios de <strong>Villa Gobernador G\u00e1lvez<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"newspaper-x-video-container\"><iframe loading=\"lazy\" title=\"Un cami\u00f3n se llev\u00f3 puesto siete autos y una moto\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/Tx7bIJtxfKg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n<div class=\"newspaper-x-tags\"><strong>TAGS: <\/strong><span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/noticias-de-vgg\" rel=\"tag\">Noticias de VGG<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/santa-fe\" rel=\"tag\">Santa Fe<\/a><\/span><a href=\"https:\/\/www.rosarioalerta.com.ar\/site\/archivos\/tag\/vgg\" rel=\"tag\">VGG<\/a> <\/div>","protected":false},"excerpt":{"rendered":"<p>Como saldo hubo varios heridos y una mujer falleci\u00f3 a pesar de los esfuerzos de los profesionales de la salud En horas de este mediod\u00eda, un espectacular siniestro vial se registr\u00f3 en Villa Gobernador G\u00e1lvez, en las inmediaciones de San Mart\u00edn y General L\u00f3pez, donde se encontraban siete automovilistas y una moto con dos ocupantes, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10405,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[17,6,21,14,10],"tags":[94,65,60],"class_list":["post-10404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-heridos","category-homicidios","category-noticias","category-policiales","category-siniestros-viales","tag-noticias-de-vgg","tag-santa-fe","tag-vgg"],"_links":{"self":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/10404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/comments?post=10404"}],"version-history":[{"count":1,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/10404\/revisions"}],"predecessor-version":[{"id":10406,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/posts\/10404\/revisions\/10406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media\/10405"}],"wp:attachment":[{"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/media?parent=10404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/categories?post=10404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosarioalerta.com.ar\/site\/wp-json\/wp\/v2\/tags?post=10404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}